{"id":225,"count":1,"description":"","link":"https:\/\/www.bottigliedivetro.it\/en\/project_tag\/bonda-en\/","name":"bonda","slug":"bonda-en","taxonomy":"project_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.4.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>bonda Archivi - Bottiglie di vetro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bottigliedivetro.it\/en\/project_tag\/bonda-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"bonda Archivi - Bottiglie di vetro\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bottigliedivetro.it\/en\/project_tag\/bonda-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Bottiglie di vetro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bottigliedivetro.it\/#website\",\"url\":\"https:\/\/www.bottigliedivetro.it\/\",\"name\":\"Bottiglie di vetro\",\"description\":\"La Vetraria di Pescia S.a.S produce e rivende bottiglie in vetro di vari colori, damigiane in vetro e accessori per le bottiglie.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.bottigliedivetro.it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.bottigliedivetro.it\/en\/project_tag\/bonda-en\/#webpage\",\"url\":\"https:\/\/www.bottigliedivetro.it\/en\/project_tag\/bonda-en\/\",\"name\":\"bonda Archivi - Bottiglie di vetro\",\"isPartOf\":{\"@id\":\"https:\/\/www.bottigliedivetro.it\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.bottigliedivetro.it\/en\/project_tag\/bonda-en\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bottigliedivetro.it\/en\/project_tag\/bonda-en\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.bottigliedivetro.it\/en\/project_tag\/bonda-en\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.bottigliedivetro.it\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"bonda\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"bonda Archivi - Bottiglie di vetro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bottigliedivetro.it\/en\/project_tag\/bonda-en\/","og_locale":"en_US","og_type":"article","og_title":"bonda Archivi - Bottiglie di vetro","og_url":"https:\/\/www.bottigliedivetro.it\/en\/project_tag\/bonda-en\/","og_site_name":"Bottiglie di vetro","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.bottigliedivetro.it\/#website","url":"https:\/\/www.bottigliedivetro.it\/","name":"Bottiglie di vetro","description":"La Vetraria di Pescia S.a.S produce e rivende bottiglie in vetro di vari colori, damigiane in vetro e accessori per le bottiglie.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bottigliedivetro.it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"CollectionPage","@id":"https:\/\/www.bottigliedivetro.it\/en\/project_tag\/bonda-en\/#webpage","url":"https:\/\/www.bottigliedivetro.it\/en\/project_tag\/bonda-en\/","name":"bonda Archivi - Bottiglie di vetro","isPartOf":{"@id":"https:\/\/www.bottigliedivetro.it\/#website"},"breadcrumb":{"@id":"https:\/\/www.bottigliedivetro.it\/en\/project_tag\/bonda-en\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bottigliedivetro.it\/en\/project_tag\/bonda-en\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.bottigliedivetro.it\/en\/project_tag\/bonda-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bottigliedivetro.it\/en\/"},{"@type":"ListItem","position":2,"name":"bonda"}]}]}},"_links":{"self":[{"href":"https:\/\/www.bottigliedivetro.it\/en\/wp-json\/wp\/v2\/project_tag\/225"}],"collection":[{"href":"https:\/\/www.bottigliedivetro.it\/en\/wp-json\/wp\/v2\/project_tag"}],"about":[{"href":"https:\/\/www.bottigliedivetro.it\/en\/wp-json\/wp\/v2\/taxonomies\/project_tag"}],"wp:post_type":[{"href":"https:\/\/www.bottigliedivetro.it\/en\/wp-json\/wp\/v2\/project?project_tag=225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}